{"id":19605,"date":"2019-01-22T10:03:44","date_gmt":"2019-01-23T14:17:29","guid":{"rendered":"http:\/\/www.makte.it\/uncategorized\/metallo-grigio-blu\/"},"modified":"2019-01-24T15:43:03","modified_gmt":"2019-01-24T14:43:03","slug":"metallo-grigio-blu","status":"publish","type":"product","link":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/","title":{"rendered":"METALLO GRIGIO-BLU"},"content":{"rendered":"<p>Finish: 2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finish: 2 [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/\">Read More&#8230;<span class=\"screen-reader-text\"> from METALLO GRIGIO-BLU<\/span><\/a><\/p>\n","protected":false},"featured_media":7011,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":["post-19605","product","type-product","status-publish","has-post-thumbnail","product_cat-catalogue","first","outofstock","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>METALLO GRIGIO-BLU | Makte<\/title>\n<meta name=\"description\" content=\"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"METALLO GRIGIO-BLU | Makte\" \/>\n<meta property=\"og:description\" content=\"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/\" \/>\n<meta property=\"og:site_name\" content=\"Makte\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-24T14:43:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKF4771I.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/\",\"url\":\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/\",\"name\":\"METALLO GRIGIO-BLU | Makte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.makte.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/MKF4771I.jpg\",\"datePublished\":\"2019-01-23T14:17:29+00:00\",\"dateModified\":\"2019-01-24T14:43:03+00:00\",\"description\":\"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.makte.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/MKF4771I.jpg\",\"contentUrl\":\"https:\\\/\\\/www.makte.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/MKF4771I.jpg\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/catalogue\\\/metallo-grigio-blu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.makte.it\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.makte.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"METALLO GRIGIO-BLU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.makte.it\\\/en\\\/\",\"name\":\"Makte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.makte.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"METALLO GRIGIO-BLU | Makte","description":"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/","og_locale":"en_US","og_type":"article","og_title":"METALLO GRIGIO-BLU | Makte","og_description":"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.","og_url":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/","og_site_name":"Makte","article_modified_time":"2019-01-24T14:43:03+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKF4771I.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/","url":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/","name":"METALLO GRIGIO-BLU | Makte","isPartOf":{"@id":"https:\/\/www.makte.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/#primaryimage"},"image":{"@id":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKF4771I.jpg","datePublished":"2019-01-23T14:17:29+00:00","dateModified":"2019-01-24T14:43:03+00:00","description":"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.","breadcrumb":{"@id":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/#primaryimage","url":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKF4771I.jpg","contentUrl":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKF4771I.jpg","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.makte.it\/en\/catalogue\/metallo-grigio-blu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.makte.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.makte.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"METALLO GRIGIO-BLU"}]},{"@type":"WebSite","@id":"https:\/\/www.makte.it\/en\/#website","url":"https:\/\/www.makte.it\/en\/","name":"Makte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.makte.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/product\/19605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/comments?post=19605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/media\/7011"}],"wp:attachment":[{"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/media?parent=19605"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/product_brand?post=19605"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/product_cat?post=19605"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.makte.it\/en\/wp-json\/wp\/v2\/product_tag?post=19605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}