{"id":15661,"date":"2019-01-22T10:06:07","date_gmt":"2019-01-22T09:06:07","guid":{"rendered":"http:\/\/www.makte.it\/senza%20categoria\/acacia-lakeland-chiaro\/"},"modified":"2025-09-19T09:24:25","modified_gmt":"2025-09-19T07:24:25","slug":"acacia-lakeland-chiaro","status":"publish","type":"product","link":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/","title":{"rendered":"ACACIA CHIARO"},"content":{"rendered":"<p>Finitura: ST9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finitura: ST9 [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/\">Leggi di pi\u00f9&#8230;<span class=\"screen-reader-text\"> from ACACIA CHIARO<\/span><\/a><\/p>\n","protected":false},"featured_media":7114,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[24],"product_tag":[],"class_list":["post-15661","product","type-product","status-publish","has-post-thumbnail","product_cat-catalogo","first","instock","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ACACIA CHIARO | Makte<\/title>\n<meta name=\"description\" content=\"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACACIA CHIARO | Makte\" \/>\n<meta property=\"og:description\" content=\"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/\" \/>\n<meta property=\"og:site_name\" content=\"Makte\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T07:24:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKH12771I.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/\",\"url\":\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/\",\"name\":\"ACACIA CHIARO | Makte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.makte.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/MKH12771I.jpg\",\"datePublished\":\"2019-01-22T09:06:07+00:00\",\"dateModified\":\"2025-09-19T07:24:25+00:00\",\"description\":\"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.makte.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/MKH12771I.jpg\",\"contentUrl\":\"https:\\\/\\\/www.makte.it\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/MKH12771I.jpg\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/catalogo\\\/acacia-lakeland-chiaro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.makte.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.makte.it\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ACACIA CHIARO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.makte.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.makte.it\\\/it\\\/\",\"name\":\"Makte\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.makte.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACACIA CHIARO | Makte","description":"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/","og_locale":"it_IT","og_type":"article","og_title":"ACACIA CHIARO | Makte","og_description":"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.","og_url":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/","og_site_name":"Makte","article_modified_time":"2025-09-19T07:24:25+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKH12771I.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/","url":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/","name":"ACACIA CHIARO | Makte","isPartOf":{"@id":"https:\/\/www.makte.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/#primaryimage"},"image":{"@id":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKH12771I.jpg","datePublished":"2019-01-22T09:06:07+00:00","dateModified":"2025-09-19T07:24:25+00:00","description":"Scopri tutti i prodotti presenti su Makte e lasciati ispirare dal nostro innovativo strumento di consulenza.","breadcrumb":{"@id":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/#primaryimage","url":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKH12771I.jpg","contentUrl":"https:\/\/www.makte.it\/wp-content\/uploads\/2018\/12\/MKH12771I.jpg","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.makte.it\/it\/catalogo\/acacia-lakeland-chiaro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.makte.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.makte.it\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"ACACIA CHIARO"}]},{"@type":"WebSite","@id":"https:\/\/www.makte.it\/it\/#website","url":"https:\/\/www.makte.it\/it\/","name":"Makte","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.makte.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/product\/15661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/comments?post=15661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/media\/7114"}],"wp:attachment":[{"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/media?parent=15661"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/product_brand?post=15661"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/product_cat?post=15661"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.makte.it\/it\/wp-json\/wp\/v2\/product_tag?post=15661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}